{"id":61464,"date":"2018-03-12T15:55:15","date_gmt":"2018-03-12T14:55:15","guid":{"rendered":"https:\/\/www.fup-ag.com\/interim-sozietaet\/"},"modified":"2025-04-30T10:33:53","modified_gmt":"2025-04-30T08:33:53","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.fup-ag.com\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"<div class=\"zw-cgb zw-cgb__120 zw-header-standard-block is-first-block    show-gradient text-boxed\"><div class=\"bg-image\"><picture><img decoding=\"sync\" loading=\"eager\" fetchPriority=\"high\" id=\"zwi_69943\" class=\"zw-cgb__image\" src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAQAAAC1HAwCAAAAC0lEQVR42mNkYAAAAAYAAjCB0C8AAAAASUVORK5CYII=\" alt=\"\" onload=\"zwHeaderPictureDone(this,'pre_69943', 'pre_69943')\"><source id=\"LCP_69943\"><\/picture><\/div><div class=\"container zw-cgb-content zw-cgb__header-content-wrapper\"><h1 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">F&amp;P Executive Solutions AG<\/span><\/h1><p class=\"zw-cgb__fulltext zw-cgb__content\">F&amp;P Executive Solutions AG has stood for first-class interim management, consulting and project management since 2009<\/p><\/div>\n        <\/div><!-- .zw-cgb .zw-header-standard -->\n\n\n    <div class=\"zw-cgb zw-cgb__000  zw-cgb_textblock  default-margin  b_standart  zw-t-l\">\n            <div class=\"container zw-cgb-content\">\n        <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">15 years of F&amp;P Executive Solutions!<\/span><\/h2>              <\/div>\n    <\/div>\n\n\n\n\n    <div class=\"zw-cgb zw-cgb__050  infoblock default-margin  show-gradient b_black \">\n            <div class=\"container-fluid\">\n        <div class=\"row\">\n          <div class=\"zw-cgb__image-col col-12 col-md-6 col-lg-5 col-xl-4 \">\n            <div class=\"zw-cgb zw-cgb__image-wrapper\">\n              <picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1-480x176.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1-768x282.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1-1000x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1-1024x375.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1-1440x528.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_104832\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/fup-header-news-1.jpg\" alt=\"\"><\/picture>            <\/div>\n          <\/div>\n          <div class=\"zw-cgb__content-col col-12 col-md-6 col-lg-7 col-xl-8\">\n            <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">Our team<\/span><\/h2><p class=\"zw-cgb__fulltext \">Discover our network of first-class experts<\/p><div class=\"zw-cgb zw-cgb__zw-blocks-zw-button-block\">\n    <div class=\"zw-cgb zw-cgb__005 buttonBlock default-margin \">\n            <div class=\"zw-button-container \"><div class=\"zw-cgb zw-cgb-button-container \"><a  class=\"zw-cgb__btn btn btn-primary btn-default-color\" href=\"https:\/\/www.fup-ag.com\/team\/experten\/\" title=\"Get to know the team\">Get to know the team<\/a><\/div><\/div>    <\/div>\n\n<\/div>          <\/div><!-- .row -->\n        <\/div><!-- .row -->\n      <\/div><!-- .container-fluid -->\n    <\/div>\n\n\n\n\n    <div class=\"zw-cgb zw-cgb__050  infoblock default-margin  show-gradient b_black \">\n            <div class=\"container-fluid\">\n        <div class=\"row\">\n          <div class=\"zw-cgb__image-col col-12 col-md-6 col-lg-5 col-xl-4 order-md-2\">\n            <div class=\"zw-cgb zw-cgb__image-wrapper\">\n              <picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7-480x320.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7-768x512.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7-990x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_65452\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2022\/11\/DDIM.kongress-2022_7.jpg\" alt=\"\"><\/picture>            <\/div>\n          <\/div>\n          <div class=\"zw-cgb__content-col col-12 col-md-6 col-lg-7 col-xl-8\">\n            <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">Impressions from F&amp;P<\/span><\/h2><p class=\"zw-cgb__fulltext \">Here you will find event impressions from F&amp;P customer and partner events<\/p><div class=\"zw-cgb zw-cgb__zw-blocks-zw-button-block\">\n    <div class=\"zw-cgb zw-cgb__005 buttonBlock default-margin \">\n            <div class=\"zw-button-container \"><div class=\"zw-cgb zw-cgb-button-container \"><a  class=\"zw-cgb__btn btn btn-primary btn-default-color\" href=\"https:\/\/www.fup-ag.com\/ueber-uns\/impressionen\/\" title=\"Learn more\">Learn more<\/a><\/div><\/div>    <\/div>\n\n<\/div>          <\/div><!-- .row -->\n        <\/div><!-- .row -->\n      <\/div><!-- .container-fluid -->\n    <\/div>\n\n\n\n\n    <div class=\"zw-cgb zw-cgb__050  infoblock default-margin  show-gradient b_black \">\n            <div class=\"container-fluid\">\n        <div class=\"row\">\n          <div class=\"zw-cgb__image-col col-12 col-md-6 col-lg-5 col-xl-4 \">\n            <div class=\"zw-cgb zw-cgb__image-wrapper\">\n              <picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_66784\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/04\/FuP-Veroeffentlichungen-Downloads.jpg\" alt=\"\"><\/picture>            <\/div>\n          <\/div>\n          <div class=\"zw-cgb__content-col col-12 col-md-6 col-lg-7 col-xl-8\">\n            <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">Publications<\/span><\/h2><p class=\"zw-cgb__fulltext \">Downloads on our firm and selected partners and studies<\/p><div class=\"zw-cgb zw-cgb__zw-blocks-zw-button-block\">\n    <div class=\"zw-cgb zw-cgb__005 buttonBlock default-margin \">\n            <div class=\"zw-button-container \"><div class=\"zw-cgb zw-cgb-button-container \"><a  class=\"zw-cgb__btn btn btn-primary btn-default-color\" href=\"https:\/\/www.fup-ag.com\/ueber-uns\/veroeffentlichungen\/\" title=\"To the downloads\">To the downloads<\/a><\/div><\/div>    <\/div>\n\n<\/div>          <\/div><!-- .row -->\n        <\/div><!-- .row -->\n      <\/div><!-- .container-fluid -->\n    <\/div>\n\n\n\n<div class=\"zw-cgb zw-cgb__025  zw-cgb__025-wrapper default-margin  b_standart \"><div class=\"bg-image\"><\/div><div class=\"container zw-cgb-content\"><div class=\"row\"><div class=\"col-12 columnmaster-inner-content\"><div class=\"row \">    <div class=\"zw-cgb zw-cgb__025-content col-lg-6 zw-cgb__col  zw-t-l\">\n    <a name=\"922be9d8_05de_4b3f_bcb2_4fe500656f55\" class=\"jumpAnchor\" ><\/a>      <div class=\"content-container \">\n        <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__preheadline\">Consulting &amp; Interim Management Solutions since 2009<\/span><span class=\"zw-cgb__headline\">F&amp;P Executive Solutions AG<\/span><\/h2><p class=\"zw-cgb__fulltext \">Since 2009, freelance consultants, project and interim managers have joined forces under the F&amp;P brand. All partners in the firm have at least 10 years of industry experience in operational management positions.<\/p><p class=\"zw-cgb__fulltext \">Our <a href=\"https:\/\/www.fup-ag.com\/taetigkeitsfelder\/\">know-how<\/a> can be used individually or bundled in a team for the most demanding, cross-divisional mandates.<\/p>      <\/div>\n    <\/div>\n    <div class=\"zw-cgb zw-cgb__025-content col-lg-6 zw-cgb__col  zw-t-l\">\n    <a name=\"907705de_76c2_45c7_a6df_69188ff1ca82\" class=\"jumpAnchor\" ><\/a>      <div class=\"content-container \">\n        <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__preheadline\">F&amp;P Executive Solutions AG<\/span><span class=\"zw-cgb__headline\">First Partner AG on the interim market<\/span><\/h2><p class=\"zw-cgb__fulltext \">Since April 2020, F&amp;P Executive Solutions AG has also been operating as the operational sister company of the partnership company F&amp;P Executive Solutions, which is therefore well-known in the interim management market.<\/p><p class=\"zw-cgb__fulltext \">Thanks to our numerous <a href=\"https:\/\/www.fup-ag.com\/en\/cooperation-partner\/\">cooperation partners<\/a>, we have access to up to 10,000 quality-assured experts.<\/p>      <\/div>\n    <\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"zw-cgb zw-cgb__510 iconsblock-wrapper  default-margin \"><div class=\"container zw-cgb-content\"><div class=\"row\"><div class=\"col-xl-7\"><h2 class=\"zw-cgb__headline\">We are a member of these associations<\/h2><\/div><\/div><div class=\"row zw-cgb__icon-row justify-content-center\">\n<div class=\"col-6 col-md-4 col-xl-3 flex-xl-fill zw-cgb iconsblock default-margin  \">\n    <div class=\"b_standart\">\n          <div class=\"zw-cgb__icon-wrapper\"><a href=\"https:\/\/ddim.de\/\" target=\"_blank\" rel=\"noopener\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner-480x360.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner-642x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_104113\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ddim-partner.jpg\" alt=\"\"><\/picture><\/a><\/div>\n          <div class=\"ms-3 text-center\"><\/div>\n        <\/div><\/div>\n\n\n<div class=\"col-6 col-md-4 col-xl-3 flex-xl-fill zw-cgb iconsblock default-margin  \">\n    <div class=\"b_standart\">\n          <div class=\"zw-cgb__icon-wrapper\"><a href=\"https:\/\/www.ifus-institut.de\/\" target=\"_blank\" rel=\"noopener\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner-480x360.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner-642x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_104095\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/ifus-partner.jpg\" alt=\"\"><\/picture><\/a><\/div>\n          <div class=\"ms-3 text-center\"><\/div>\n        <\/div><\/div>\n\n\n<div class=\"col-6 col-md-4 col-xl-3 flex-xl-fill zw-cgb iconsblock default-margin  \">\n    <div class=\"b_standart\">\n          <div class=\"zw-cgb__icon-wrapper\"><a href=\"https:\/\/www.bvmw.de\/\" target=\"_blank\" rel=\"noopener\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner-480x360.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner-642x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_104093\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/der-mittelstand-partner.jpg\" alt=\"\"><\/picture><\/a><\/div>\n          <div class=\"ms-3 text-center\"><\/div>\n        <\/div><\/div>\n\n\n<div class=\"col-6 col-md-4 col-xl-3 flex-xl-fill zw-cgb iconsblock default-margin  \">\n    <div class=\"b_standart\">\n          <div class=\"zw-cgb__icon-wrapper\"><a href=\"https:\/\/www.brsi.international\/\" target=\"_blank\" rel=\"noopener\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner-480x360.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner-642x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_104111\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/10\/brsi-partner.jpg\" alt=\"\"><\/picture><\/a><\/div>\n          <div class=\"ms-3 text-center\"><\/div>\n        <\/div><\/div>\n\n<\/div><\/div><\/div>\n\n<div class=\"zw-cgb zw-cgb__010 calltoaction default-margin  zw-rebase-landscape-pos-default  zw-t-l\"><div class=\"container zw-cgb-content\">\n        <div class=\"row align-items-center\">\n          <div class=\"col-lg-5\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere-150x150.png 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere-480x376.png 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere-768x602.png 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere-794x400.png 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere.png 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere.png 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere.png 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere.png 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_103706\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/Broschuere.png\" alt=\"\"><\/picture><\/div>\n          <div class=\"col-lg-6 offset-lg-1\"><h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__preheadline\">F&amp;P Brochure<\/span><span class=\"zw-cgb__headline\">In our brochure you will find information on the topic of restructuring &amp; business transformation<\/span><\/h2><div class=\"zw-cgb zw-cgb__zw-blocks-zw-button-block\">\n    <div class=\"zw-cgb zw-cgb__005 buttonBlock default-margin btn-white\">\n            <div class=\"zw-button-container \"><div class=\"zw-cgb zw-cgb-button-container \"><a class=\"zw-cgb__btn btn btn-primary btn-default-color\" href=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/07\/FuP-Kundenbroschuere_Sanierung-Restructuring.pdf\" title=\"Download brochure\">Download brochure<\/a><\/div><\/div>    <\/div>\n\n<\/div><\/div>\n        <\/div>\n      <\/div>\n    <\/div><!-- .zw-cgb .calltoaction-->\n\n\n    <div class=\"zw-cgb zw-cgb__000  zw-cgb_textblock  default-margin  b_standart  zw-t-l\">\n            <div class=\"container zw-cgb-content\">\n        <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">About us<\/span><\/h2><p class=\"zw-cgb__fulltext \">Get to know our company and our accredited selection process for F&amp;P interim managers and consultants.<\/p>              <\/div>\n    <\/div>\n\n\n\n\n    <div class=\"zw-cgb zw-cgb__200  videoEmbedBlock \">\n      <a name=\"b9b952b1-9991-4b26-aa75-ef64b4820be3\" class=\"jumpAnchor\" ><\/a>       <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGlmcmFtZSB0aXRsZT0iRiZhbXA7UCBFeGVjdXRpdmUgU29sdXRpb25zIEFHIHwgQ29uc3VsdGluZyAmYW1wOyBJbnRlcmltIE1hbmFnZW1lbnQgQ29tcGFueSIgd2lkdGg9Ijk2MCIgaGVpZ2h0PSI1NDAiIHNyYz0iaHR0cHM6Ly93d3cueW91dHViZS1ub2Nvb2tpZS5jb20vZW1iZWQvQnFnWEZLbFRRcFE\/ZmVhdHVyZT1vZW1iZWQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvdz0iYWNjZWxlcm9tZXRlcjsgYXV0b3BsYXk7IGNsaXBib2FyZC13cml0ZTsgZW5jcnlwdGVkLW1lZGlhOyBneXJvc2NvcGU7IHBpY3R1cmUtaW4tcGljdHVyZTsgd2ViLXNoYXJlIiByZWZlcnJlcnBvbGljeT0ic3RyaWN0LW9yaWdpbi13aGVuLWNyb3NzLW9yaWdpbiIgYWxsb3dmdWxsc2NyZWVuPjwvaWZyYW1lPg==\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.fup-ag.com\/wp-content\/uploads\/borlabs-cookie\/1\/yt_BqgXFKlTQpQ_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">You are currently viewing a placeholder content from <strong>YouTube<\/strong>. To access the actual content, click the button below. Please note that doing so will share data with third-party providers.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">More Information<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Unblock content<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Accept required service and unblock content<\/a> <\/div> <\/div> <\/div><\/div>    <\/div>\n\n\n\n<div class=\"zw-cgb zw-cgb__025  zw-cgb__025-wrapper default-margin  b_standart \"><div class=\"bg-image\"><\/div><div class=\"container zw-cgb-content\"><div class=\"row\"><div class=\"col-12 columnmaster-inner-content\"><div class=\"row \">    <div class=\"zw-cgb zw-cgb__025-content col-lg-6 zw-cgb__col  zw-t-l\">\n    <a name=\"dc4afa4b_ad3d_4cb4_8b54_1d5097bf8ef8\" class=\"jumpAnchor\" ><\/a>      <div class=\"content-container \">\n        <h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">Industry experts for industry &amp; trade and other key sectors<\/span><\/h2><div class=\"zw-cgb zw-cgb__zw-blocks-zw-button-block\">\n    <div class=\"zw-cgb zw-cgb__005 buttonBlock default-margin \">\n            <div class=\"zw-button-container \"><div class=\"zw-cgb zw-cgb-button-container \"><a class=\"zw-cgb__btn btn btn-primary btn-default-color\" href=\"https:\/\/www.fup-ag.com\/kontakt-2\/\" title=\"Find your expert now\">Find your expert now<\/a><\/div><\/div>    <\/div>\n\n<\/div>      <\/div>\n    <\/div>\n    <div class=\"zw-cgb zw-cgb__025-content col-lg-6 zw-cgb__col  zw-t-l\">\n    <a name=\"fb2d1b78_0175_45dd_91e6_49676b3ff2ed\" class=\"jumpAnchor\" ><\/a>      <div class=\"content-container \">\n        <p class=\"zw-cgb__fulltext \">As shareholders, our partners jointly contribute to the growth of our clients in the industry &amp; trade, pharmaceuticals, private equity, IT and industrial engineering sectors, as well as that of our company.<\/p><p class=\"zw-cgb__fulltext \">Our deliberately chosen legal form guarantees the highest quality standards for decision-makers.<\/p><p class=\"zw-cgb__fulltext \">F&amp;P&#8217;s services stand for excellent best practice solutions for the most demanding industrial, commercial and private equity clients.<\/p><p class=\"zw-cgb__fulltext \">The synergy of commercial, technical and scientific training of the partners, in addition to many years of professional and industry-specific experience and specialization, form the basis for jointly developed, highly efficient industry solutions with sophisticated methods, tools and implementation concepts.<\/p>      <\/div>\n    <\/div>\n<\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"zw-cgb zw-cgb__620 zw-header-simple   b_black \"><div class=\"zw-cgb__background-image-wrapper\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1-480x171.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1-768x273.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1-1000x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1-1024x364.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1-1440x512.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_103655\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2024\/09\/hamburg1.jpg\" alt=\"\"><\/picture><div class=\"zw-cgb__image-overlay\"><\/div><\/div><div class=\"container zw-cgb__content-wrapper\"><div class=\"row h-100 justify-content-between \"><div class=\"col-lg-6 col-xl-6 align-self-center zw-cgb__content-col\"><h3 class=\"zw-cgb__headline zw-cgb__content\">Find the right expert now<\/h3><p class=\"zw-cgb__fulltext zw-cgb__content\">Use our form to describe your upcoming project. We will get back to you within 24 hours.<\/p><div class=\"zw-cgb zw-cgb__zw-blocks-zw-button-block\">\n    <div class=\"zw-cgb zw-cgb__005 buttonBlock default-margin \">\n            <div class=\"zw-button-container \"><div class=\"zw-cgb zw-cgb-button-container \"><a class=\"zw-cgb__btn btn btn-primary btn-default-color\" href=\"https:\/\/www.fup-ag.com\/kontakt-2\/\" title=\"Find your expert now\">Find your expert now<\/a><\/div><\/div>    <\/div>\n\n<\/div><\/div><div class=\"col-lg-6 col-xl-5 align-self-end text-center\"><div class=\"zw-cgb__decorator-image-wrapper \"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/03\/FuP-Experten-Banner-Freisteller-Experten-480x461.png 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/03\/FuP-Experten-Banner-Freisteller-Experten-480x461.png 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/03\/FuP-Experten-Banner-Freisteller-Experten-768x738.png 1024w\" sizes=\"(max-width: 480px) 320px, (max-width: 768px) 600px, 960px\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_66380\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/03\/FuP-Experten-Banner-Freisteller-Experten.png\" alt=\"\"><\/picture><\/div><\/div><\/div><\/div><\/div><!-- .zw-cgb .zw-header-simple -->\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<div class=\"zw-cgb zw-cgb__120 zw-header-standard-block     show-gradient text-boxed\">\n<div class=\"bg-image\"><picture><source srcset=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner-150x150.jpg 150w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner-480x175.jpg 480w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner-768x280.jpg 768w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner-1000x400.jpg 1000w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner-1024x373.jpg 1024w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner-1440x525.jpg 1440w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner.jpg 1920w, https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner.jpg 9999w\" sizes=\"(max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1024px) 100vw, (max-width: 1440px) 100vw, 100vw\" ><img decoding=\"async\" loading=\"lazy\" id=\"zwi_69943\" class=\"zw-cgb__image\" src=\"https:\/\/www.fup-ag.com\/wp-content\/uploads\/2023\/12\/fup-team-banner.jpg\" alt=\"\"><\/picture><\/div>\n<div class=\"container zw-cgb-content zw-cgb__header-content-wrapper\">\n<h2 class=\"zw-cgb__headlines\"><span class=\"zw-cgb__headline\">F&amp;P Executive Solutions AG<\/span><\/h2>\n<p class=\"zw-cgb__fulltext zw-cgb__content\">F&amp;P Executive Solutions AG has stood for first-class interim management, consulting and project management since 2009<\/p>\n<\/div><\/div>\n<p><!-- .zw-cgb .zw-header-standard --><\/p>\n","protected":false},"author":1,"featured_media":64605,"parent":0,"menu_order":600,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"63716,64895,63804,63809","_relevanssi_noindex_reason":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"expertise":[],"service":[],"industry":[],"class_list":["post-61464","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/pages\/61464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/comments?post=61464"}],"version-history":[{"count":11,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/pages\/61464\/revisions"}],"predecessor-version":[{"id":114060,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/pages\/61464\/revisions\/114060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/media\/64605"}],"wp:attachment":[{"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/media?parent=61464"}],"wp:term":[{"taxonomy":"expertise","embeddable":true,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/expertise?post=61464"},{"taxonomy":"service","embeddable":true,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/service?post=61464"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.fup-ag.com\/en\/wp-json\/wp\/v2\/industry?post=61464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}